{"id":483,"date":"2008-07-20T16:45:31","date_gmt":"2008-07-20T16:45:31","guid":{"rendered":"http:\/\/erinnerungshort.de\/blog\/jay-walsh-und-florence-uber-ko"},"modified":"2015-12-09T20:01:14","modified_gmt":"2015-12-09T18:01:14","slug":"jay-walsh-und-florence-uber-ko","status":"publish","type":"post","link":"https:\/\/erinnerungshort.de\/blog\/jay-walsh-und-florence-uber-ko\/","title":{"rendered":"Jay Walsh und Florence \u00fcber Kommunikation"},"content":{"rendered":"<p>&#8222;Telling the Wikipedia story&#8220; ist der Titel des Talks von Jay Walsh, Kommunikationschef der Foundation. Er plaudert \u00fcber seinen Job und die Herausforderungen in der externen oder internen (zur Community) Kommunikation. Schon zum zweiten Mal wird der Blog-Planet (<a href=\"http:\/\/en.planet.wikimedia.org\/)\">http:\/\/en.planet.wikimedia.org\/)<\/a> als Super-Werkzeug zur Information erw\u00e4hnt (vorher schon von Florence Devouard). Kul, der neue Chef f\u00fcr Business Development, ist \u00fcbrigens auch im Raum; er erkl\u00e4rt auf Nachfrage, welche M\u00f6glichkeiten der (nicht nur finanzieller) F\u00f6rderung von &#8222;drau\u00dfen&#8220; au\u00dferhalb von Fundraising geben kann. Im Publikum versteht man vereinzelt nicht so ganz, warum keine Werbung auf WP geschaltet werden kann. Er k\u00fcndigt f\u00fcr die n\u00e4chsten Monate ein paar neue Projekte an. (&#8222;not all businesses are evil&#8220;)<\/p>\n<p>W\u00e4hrend Kul also f\u00fcrs Gesch\u00e4ft zust\u00e4ndig ist, mu\u00df Jay erkl\u00e4ren, was wir machen, und warum wir bestimmte Sachen nicht machen.<\/p>\n<p>Er erz\u00e4hlt von Brion, als der in den ganz fr\u00fchen Tagen noch als Ehrenamtlicher die ersten Server ans Laufen brachte, und sie am Laufen hielt. Wichtige Frage, wie man bezahlten und unbezahlten Einsatz unter einen Hut bringt &#8211; viel mehr Leute als die 15 festangestellten K\u00f6pfe der WMF machen die Arbeit der Foundation aus.<\/p>\n<p>Im Prinzip wird aber hier, ebenso wie in Florences Talk klar, da\u00df die WMF ebenso damit k\u00e4mpft, die Kommunikation mit der Community zu verbessern, wie &#8222;der Verein&#8220; in Deutschland. Eine L\u00f6sung hat niemand, aber strampeln tun wir alle&#8230;. (&#8222;bringing people together moreoften&#8220; &#8211; elya nickt mit heftig dem Kopf). Oder ist es vielleicht zuviel Information auf zuvielen Kan\u00e4len? Florence hat 42 Mailinglisten abonniert. Starker Beifall bei dem Vorschlag, die Mailinglisten massiv zu reduzieren.<\/p>\n<p>Noch eine Minute, und es geht schon zur Abschlu\u00dfveranstaltung, und heute abend gibt es eine Party der Volunteers, also raus aus der Bibliotek.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>&#8222;Telling the Wikipedia story&#8220; ist der Titel des Talks von Jay Walsh, Kommunikationschef der Foundation. Er plaudert \u00fcber seinen Job und die Herausforderungen in der externen oder internen (zur Community) Kommunikation. Schon zum zweiten Mal wird d&#8230;<\/p>\n","protected":false},"author":6,"featured_media":0,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"ngg_post_thumbnail":0,"footnotes":""},"categories":[1,52,54,59],"tags":[24,25,26],"class_list":{"0":"post-483","1":"post","2":"type-post","3":"status-publish","4":"format-standard","6":"category-allgemein","7":"category-posterous","8":"category-wikimania-2008","9":"category-wikipedia-2","10":"tag-foundation","11":"tag-kommunikation","12":"tag-wikimania","13":"entry"},"_links":{"self":[{"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/posts\/483","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/users\/6"}],"replies":[{"embeddable":true,"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/comments?post=483"}],"version-history":[{"count":5,"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/posts\/483\/revisions"}],"predecessor-version":[{"id":763,"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/posts\/483\/revisions\/763"}],"wp:attachment":[{"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/media?parent=483"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/categories?post=483"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/erinnerungshort.de\/blog\/wp-json\/wp\/v2\/tags?post=483"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}